{"id":28580,"date":"2011-11-11T18:14:27","date_gmt":"2011-11-11T20:14:27","guid":{"rendered":"http:\/\/www.r2cpress.com.br\/v1\/?p=28580"},"modified":"2011-11-11T18:14:27","modified_gmt":"2011-11-11T20:14:27","slug":"ii-cavalverao-3","status":"publish","type":"post","link":"https:\/\/www.r2cpress.com.br\/v1\/2011\/11\/11\/ii-cavalverao-3\/","title":{"rendered":"II Cavalver\u00e3o"},"content":{"rendered":"<p>Rabat boa tarde,<\/p>\n<p>Para abrilhantar mais a nossa cavalgada, e mostrar a nossa cidade para os cavaleiros que vem de diversas cidade do Brasil, a <strong>sa\u00edda da II Cavalver\u00e3o, mudou para Centro de Conven\u00e7\u00f5es<\/strong>, conforme est\u00e1 no arquivo de JPEG, favor postar em seu site a nova sa\u00edda da cavalgada, mais uma vez, muito obrigado pelo seu apoio.<\/p>\n<p><center> <a href=\"http:\/\/www.r2cpress.com.br\/v1\/wp-content\/uploads\/II-Cavalver\u00e3o-Centro-de-Conven\u00e7\u00f5es_.jpg\"><img loading=\"lazy\" src=\"http:\/\/www.r2cpress.com.br\/v1\/wp-content\/uploads\/II-Cavalver\u00e3o-Centro-de-Conven\u00e7\u00f5es_.jpg\" alt=\"\" title=\"II Cavalver\u00e3o - Centro de Conven\u00e7\u00f5es_\" width=\"500\" height=\"353\" class=\"aligncenter size-full wp-image-28581\" srcset=\"https:\/\/www.r2cpress.com.br\/v1\/wp-content\/uploads\/II-Cavalver\u00e3o-Centro-de-Conven\u00e7\u00f5es_.jpg 500w, https:\/\/www.r2cpress.com.br\/v1\/wp-content\/uploads\/II-Cavalver\u00e3o-Centro-de-Conven\u00e7\u00f5es_-300x211.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/center><\/p>\n<p>Sds<\/p>\n<p>Marcell Tavares<\/p>\n<p>Coordenador do Evento<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rabat boa tarde, Para abrilhantar mais a nossa cavalgada, e mostrar a nossa cidade para os cavaleiros que vem de diversas cidade do Brasil, a sa\u00edda da II Cavalver\u00e3o, mudou para Centro de Conven\u00e7\u00f5es, conforme est\u00e1 no arquivo de JPEG, favor postar em seu site a nova sa\u00edda da cavalgada, mais uma vez, muito obrigado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[10],"tags":[],"_links":{"self":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts\/28580"}],"collection":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/comments?post=28580"}],"version-history":[{"count":2,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts\/28580\/revisions"}],"predecessor-version":[{"id":28583,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts\/28580\/revisions\/28583"}],"wp:attachment":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/media?parent=28580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/categories?post=28580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/tags?post=28580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}