{"id":88359,"date":"2014-11-14T08:04:34","date_gmt":"2014-11-14T11:04:34","guid":{"rendered":"http:\/\/www.r2cpress.com.br\/v1\/?p=88359"},"modified":"2014-11-14T08:04:34","modified_gmt":"2014-11-14T11:04:34","slug":"no-gotas-de-paz-210","status":"publish","type":"post","link":"https:\/\/www.r2cpress.com.br\/v1\/2014\/11\/14\/no-gotas-de-paz-210\/","title":{"rendered":"No GOTAS DE PAZ"},"content":{"rendered":"<h1 style=\"text-align: center;\"><span style=\"color: #000080;\"><strong>Um dia\u2026<\/strong><\/span><\/h1>\n<p style=\"text-align: center;\">Um dia voc\u00ea vai ver que n\u00e3o valeu a pena tanta correria,<br \/>\npara ganhar dinheiro e n\u00e3o usufruir.<br \/>\nVai ver que o tempo passou e o cansa\u00e7o tomou conta de seu corpo.<br \/>\nVai ver que, mesmo rodeado de muita gente, voc\u00ea se sente s\u00f3.<br \/>\nUm dia voc\u00ea vai se recolher ao seu quarto, e ter vontade de abra\u00e7ar o travesseiro,<br \/>\nporque n\u00e3o sobrou ningu\u00e9m pra abra\u00e7ar.<br \/>\nVai ver que, entrando numa roda viva,\u00a0voc\u00ea n\u00e3o \u00e9 mais dono do tempo que dizem<br \/>\nque \u00e9 seu, e que n\u00e3o pode ced\u00ea-lo a qualquer um.<br \/>\nVai ver que o carro j\u00e1 est\u00e1 se tornando um problema, e n\u00e3o um conforto.<br \/>\nO telefone \u00e9 chato, a gravata incomoda\u2026<br \/>\nPor mais que tente se livrar de tudo, \u00e9 um escravo,\u00a0e ainda assim invejado por muitos.<br \/>\nVai ver que n\u00e3o valeu a pena os anos sem f\u00e9rias, sem descanso.<br \/>\nVai ver que n\u00e3o tem mais ilus\u00f5es, e a esperan\u00e7a anda com vontade de dormir.<br \/>\nUm dia voc\u00ea vai ver que passou pela vida sem viver.<br \/>\nFreq\u00fcentou o mundo sem saber porqu\u00ea.<br \/>\nRodou, rodou, e n\u00e3o saiu do lugar. Pensou que foi, mas ficou.<br \/>\nTeve tudo e n\u00e3o sentiu nada.<br \/>\nUm dia voc\u00ea ver\u00e1 que o tempo escoa t\u00e3o r\u00e1pido,<br \/>\ncomo a areia fina pelos seus dedos.<br \/>\nVai ver que resta parar e gritar de cima de um edif\u00edcio: &#8220;Chega!!!\u201d.<br \/>\nVai ver que \u00e9 hora de sorrir, de amar, de ser da fam\u00edlia,<br \/>\nde misturar-se com as crian\u00e7as e dar a m\u00e3o ao pr\u00f3ximo.<br \/>\nAntes que seja tarde demais\u2026<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\"><strong>GOTAS DE PAZ:<\/strong><\/span><\/p>\n<p>http:\/\/www.gotasdepaz.com.br\/um-dia-2\/?utm_source=Mensagem+14%2F11%2F2014&#038;utm_medium=email&#038;utm_campaign=Mensagem+14%2F11%2F2014<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um dia\u2026 Um dia voc\u00ea vai ver que n\u00e3o valeu a pena tanta correria, para ganhar dinheiro e n\u00e3o usufruir. Vai ver que o tempo passou e o cansa\u00e7o tomou conta de seu corpo. Vai ver que, mesmo rodeado de muita gente, voc\u00ea se sente s\u00f3. Um dia voc\u00ea vai se recolher ao seu quarto, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[17],"tags":[],"_links":{"self":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts\/88359"}],"collection":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/comments?post=88359"}],"version-history":[{"count":2,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts\/88359\/revisions"}],"predecessor-version":[{"id":88361,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts\/88359\/revisions\/88361"}],"wp:attachment":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/media?parent=88359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/categories?post=88359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/tags?post=88359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}