{"id":92927,"date":"2015-04-13T00:01:50","date_gmt":"2015-04-13T03:01:50","guid":{"rendered":"http:\/\/www.r2cpress.com.br\/v1\/?p=92927"},"modified":"2015-04-12T09:40:39","modified_gmt":"2015-04-12T12:40:39","slug":"mensagem-da-semana-232","status":"publish","type":"post","link":"https:\/\/www.r2cpress.com.br\/v1\/2015\/04\/13\/mensagem-da-semana-232\/","title":{"rendered":"MENSAGEM DA SEMANA"},"content":{"rendered":"<p><strong>Caros amigos e amigas,<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>\u00a0<\/strong><strong>APRENDER<\/strong><\/p>\n<p>Tudo tem sua hora pr\u00f3pria.<\/p>\n<p>\u201cO pr\u00f3prio c\u00e9u tem hor\u00e1rio para as trevas e para a luz\u201d.<\/p>\n<p>Aprenda com a natureza!<\/p>\n<p>Se em certas horas precisamos receber, n\u00e3o se esque\u00e7a de que, noutras horas, temos obriga\u00e7\u00e3o de dar.<\/p>\n<p>Ajude, pois, mas sem querer substituir-se a quem voc\u00ea ajuda.<\/p>\n<p>Cada um precisa caminhar com seus pr\u00f3prios p\u00e9s, para aprender a viver.<\/p>\n<p>Saiba distinguir o momento oportuno de dar e de receber. (C.Torres Pastorino)<\/p>\n<p><em>Que todos tenham uma semana d<\/em>e PAZ e LUZ, repleta de SA\u00daDE e a BEN\u00c7\u00c3O misericordiosa de DEUS, que \u00e9 um Pai de infinita bondade e amor.<\/p>\n<p style=\"text-align: center;\">\u00a0<strong>Z\u00c9CARLOS JUNIOR<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Caros amigos e amigas, \u00a0APRENDER Tudo tem sua hora pr\u00f3pria. \u201cO pr\u00f3prio c\u00e9u tem hor\u00e1rio para as trevas e para a luz\u201d. Aprenda com a natureza! Se em certas horas precisamos receber, n\u00e3o se esque\u00e7a de que, noutras horas, temos obriga\u00e7\u00e3o de dar. Ajude, pois, mas sem querer substituir-se a quem voc\u00ea ajuda. Cada um [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[17],"tags":[],"_links":{"self":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts\/92927"}],"collection":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/comments?post=92927"}],"version-history":[{"count":1,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts\/92927\/revisions"}],"predecessor-version":[{"id":92928,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts\/92927\/revisions\/92928"}],"wp:attachment":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/media?parent=92927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/categories?post=92927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/tags?post=92927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}