{"id":94040,"date":"2015-06-05T09:22:45","date_gmt":"2015-06-05T12:22:45","guid":{"rendered":"http:\/\/www.r2cpress.com.br\/v1\/?p=94040"},"modified":"2015-06-05T09:22:45","modified_gmt":"2015-06-05T12:22:45","slug":"no-gotas-de-paz-360","status":"publish","type":"post","link":"https:\/\/www.r2cpress.com.br\/v1\/2015\/06\/05\/no-gotas-de-paz-360\/","title":{"rendered":"No GOTAS DE PAZ"},"content":{"rendered":"<h1 class=\"entry-title post-title\" style=\"text-align: center;\"><span style=\"color: #000080;\"><strong>Espiritos imortais<\/strong><\/span><\/h1>\n<p>Como esp\u00edritos imortais,<br \/>\nde tempos a tempos albergados na carne,<br \/>\nvemos diante de n\u00f3s a urgente tarefa da reeduca\u00e7\u00e3o moral.<br \/>\nSomos ainda Esp\u00edritos t\u00e3o imperfeitos,<br \/>\nque as fagulhas do bem a cair sobre a Terra,<br \/>\ncomo estrelas cadentes em chuva de amor,<br \/>\nsobre n\u00f3s raramente s\u00e3o percebidas,<br \/>\npor nossos cora\u00e7\u00f5es t\u00e3o atormentados.<br \/>\nE tudo isso porque ainda n\u00e3o nos habituamos ao bem.<br \/>\nA imers\u00e3o no corpo f\u00edsico vem limitar n\u00e3o somente os sentidos,<br \/>\nmais amplos da alma, mas tamb\u00e9m o h\u00e1bito,<br \/>\nmilenar de exercer julgamentos.<br \/>\nVamos educ\u00e1-los com amor. A come\u00e7ar pelos olhos,<br \/>\nvamos trein\u00e1-los para ver o bem em toda a parte.<br \/>\nPor mais degradante ou suspeita,<br \/>\na imagem que surja diante de n\u00f3s, que nossos olhos,<br \/>\ntocados pelo amor de Deus, possam cobri-la de luz,<br \/>\ne torn\u00e1-la um convite \u00e0 caridade, \u00e0 solidariedade e ao bem comum.<br \/>\nQue o mendigo n\u00e3o seja, portanto, o delinq\u00fcente;<br \/>\nmas o irm\u00e3o em maior necessidade.<br \/>\nQue o violento seja algu\u00e9m a nos clamar candura.<br \/>\nQue o salteador seja uma alma mais necessitada,<br \/>\ndaquele bem que talvez acumul\u00e1ssemos em demasia.<br \/>\nQue o assassino seja apenas um esp\u00edrito,<br \/>\nque se distanciou de Deus e suas leis de amor,<br \/>\na nos rogar complac\u00eancia e reeduca\u00e7\u00e3o.<br \/>\nQue o familiar indisciplinado seja o Esp\u00edrito,<br \/>\nem imensa dificuldade que Deus confiou ao nosso amor.<br \/>\nFa\u00e7amos aos outros como Jesus faz conosco.<br \/>\nOlhemos com olhos do bem,<br \/>\npara ver o bem do Cristo em toda parte.<\/p>\n<p><span style=\"color: #000080;\"><strong>GOTAS DE PAZ:<\/strong><\/span><\/p>\n<p>http:\/\/www.gotasdepaz.com.br\/espiritos-imortais\/?utm_source=Mensagem+05%2F06%2F2015&#038;utm_medium=email&#038;utm_campaign=Mensagem+05%2F06%2F2015<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Espiritos imortais Como esp\u00edritos imortais, de tempos a tempos albergados na carne, vemos diante de n\u00f3s a urgente tarefa da reeduca\u00e7\u00e3o moral. Somos ainda Esp\u00edritos t\u00e3o imperfeitos, que as fagulhas do bem a cair sobre a Terra, como estrelas cadentes em chuva de amor, sobre n\u00f3s raramente s\u00e3o percebidas, por nossos cora\u00e7\u00f5es t\u00e3o atormentados. E [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[17],"tags":[],"_links":{"self":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts\/94040"}],"collection":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/comments?post=94040"}],"version-history":[{"count":1,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts\/94040\/revisions"}],"predecessor-version":[{"id":94041,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts\/94040\/revisions\/94041"}],"wp:attachment":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/media?parent=94040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/categories?post=94040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/tags?post=94040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}