{"id":95689,"date":"2015-09-09T06:16:26","date_gmt":"2015-09-09T09:16:26","guid":{"rendered":"http:\/\/www.r2cpress.com.br\/v1\/?p=95689"},"modified":"2015-09-09T06:16:26","modified_gmt":"2015-09-09T09:16:26","slug":"no-gotas-de-paz-426","status":"publish","type":"post","link":"https:\/\/www.r2cpress.com.br\/v1\/2015\/09\/09\/no-gotas-de-paz-426\/","title":{"rendered":"No GOTAS DE PAZ"},"content":{"rendered":"<h1 class=\"entry-title post-title\" style=\"text-align: center;\"><span style=\"color: #0000ff;\"><strong>Preciosidades<\/strong><\/span><\/h1>\n<p>Temos muitos motivos na vida para nos sentirmos felizes, por\u00e9m, estamos sempre buscando a felicidade onde ela n\u00e3o existe. N\u00e3o pensamos no quanto \u00e9 bom poder enxergar e ver as belezas que existem no mundo, com paisagens t\u00e3o lindas que nem o melhor artista conseguiria expressar atrav\u00e9s de uma pintura. N\u00e3o valorizamos a maravilha que \u00e9 a m\u00e1quina humana, que funciona como um Universo \u00e0 parte, tudo perfeito, trabalhando em sintonia com o Universo Maior. Muitas vezes deixamos de valorizar a fam\u00edlia que temos, mesmo com suas dificuldades. \u00c9 t\u00e3o bom voltar para casa e saber que l\u00e1 entes queridos nos aguardam ansiosos. N\u00e3o nos damos conta do quanto \u00e9 bom servir, auxiliar aqueles que necessitam da nossa ajuda, sem nada esperar em troca. \u00c9 maravilhoso saber que jamais estamos desamparados e que existe um Deus, bom, justo, generoso e amoroso, que nos criou para a vida eterna. Como \u00e9 bom saber que esse Deus nos d\u00e1 infinitas oportunidades para aprendermos e crescermos como esp\u00edritos que somos. \u00c9 confortante saber que Deus sempre nos d\u00e1 o necess\u00e1rio para vivermos e cumprirmos o nosso destino. Por tudo isso sempre que se sentir insatisfeito com os outros, com a sua vida, pense nas preciosidades que possui e que n\u00e3o valoriza. Todos passam por dificuldades porque faz parte do aprendizado, mas lembremo-nos de que o bem que possu\u00edmos e o Pai maravilhoso que temos \u00e9 infinitamente maior que tudo.<\/p>\n<p><span style=\"color: #0000ff;\"><strong>GOTAS DE PAZ:<\/strong><\/span><\/p>\n<p>http:\/\/www.gotasdepaz.com.br\/preciosidades\/?utm_source=09%2F09%2F2015&#038;utm_medium=email&#038;utm_campaign=09%2F09%2F2015<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Preciosidades Temos muitos motivos na vida para nos sentirmos felizes, por\u00e9m, estamos sempre buscando a felicidade onde ela n\u00e3o existe. N\u00e3o pensamos no quanto \u00e9 bom poder enxergar e ver as belezas que existem no mundo, com paisagens t\u00e3o lindas que nem o melhor artista conseguiria expressar atrav\u00e9s de uma pintura. N\u00e3o valorizamos a maravilha [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[17],"tags":[],"_links":{"self":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts\/95689"}],"collection":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/comments?post=95689"}],"version-history":[{"count":1,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts\/95689\/revisions"}],"predecessor-version":[{"id":95690,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/posts\/95689\/revisions\/95690"}],"wp:attachment":[{"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/media?parent=95689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/categories?post=95689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.r2cpress.com.br\/v1\/wp-json\/wp\/v2\/tags?post=95689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}